{"id":797,"count":25,"description":"","link":"https:\/\/mountakhab.net\/category\/feminin\/equipe-1-f\/","name":"EQUIPE 1 F","slug":"equipe-1-f","taxonomy":"category","parent":56,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/mountakhab.net\/en\/wp-json\/wp\/v2\/categories\/797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mountakhab.net\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/mountakhab.net\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/mountakhab.net\/en\/wp-json\/wp\/v2\/categories\/56"}],"wp:post_type":[{"href":"https:\/\/mountakhab.net\/en\/wp-json\/wp\/v2\/posts?categories=797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}